{"id":11576,"date":"2026-02-12T19:25:17","date_gmt":"2026-02-12T19:25:17","guid":{"rendered":"https:\/\/lamascoteriaonline.co\/shop\/?post_type=product&#038;p=11576"},"modified":"2026-02-12T19:25:17","modified_gmt":"2026-02-12T19:25:17","slug":"nutrecat-home-8-kg","status":"publish","type":"product","link":"https:\/\/lamascoteriaonline.co\/shop\/product\/nutrecat-home-8-kg\/","title":{"rendered":"Nutrecat home  8 kg"},"content":{"rendered":"<p>No dejes pasar la oportunidad para ofrecerle a tu gato un alimento completo y muy nutritivo como NutreCat Home. Esta f\u00f3rmula cuenta con ingredientes seleccionados de f\u00e1cil digesti\u00f3n y una alta palatabilidad que combina la carne de res, pollo y pescado obteniendo el mejor sabor para deleitar a tu gato. Su excelente fuente de \u00e1cidos grasos como el omega 3 y 6, junto a la biotina y el zinc fortalecen su pelo, previenen de patolog\u00edas como la seborrea, mejora la calidad de la piel evitando inflamaciones y act\u00faan como antioxidante natural. Adem\u00e1s, junto a la vitamina C fortalecen el sistema inmune y optimizan la calcificaci\u00f3n de los huesos manteni\u00e9ndolos fuertes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No dejes pasar la oportunidad para ofrecerle a tu gato un alimento completo y muy nutritivo como NutreCat Home. Esta f\u00f3rmula cuenta con ingredientes seleccionados de f\u00e1cil digesti\u00f3n y una alta palatabilidad que combina la carne de res, pollo y pescado obteniendo el mejor sabor para deleitar a tu gato. Su excelente fuente de \u00e1cidos [&hellip;]<\/p>\n","protected":false},"featured_media":11577,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[]},"product_brand":[],"product_cat":[167],"product_tag":[],"class_list":["post-11576","product","type-product","status-publish","has-post-thumbnail","product_cat-nutrecat-alimento-seco","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/product\/11576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/comments?post=11576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/media\/11577"}],"wp:attachment":[{"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/media?parent=11576"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/product_brand?post=11576"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/product_cat?post=11576"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/product_tag?post=11576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}