{"id":10683,"date":"2024-06-01T21:15:33","date_gmt":"2024-06-01T21:15:33","guid":{"rendered":"https:\/\/lamascoteriaonline.co\/shop\/?post_type=product&#038;p=10683"},"modified":"2024-06-01T21:21:30","modified_gmt":"2024-06-01T21:21:30","slug":"br-for-dog-adulto-raza-mediana","status":"publish","type":"product","link":"https:\/\/lamascoteriaonline.co\/shop\/product\/br-for-dog-adulto-raza-mediana\/","title":{"rendered":"Br For Dog Adulto Raza Mediana"},"content":{"rendered":"<p><b>BR For Dog Pure Adulto Razas Medianas<\/b> es un alimento seco, completo para perros adultos de razas medianas.<\/p>\n<p>rroz blanco (26%), cordero deshidratado (13,5%), pollo deshidratado (13,5%), grasa animal (pollo), prote\u00edna de pollo hidrolizado, pulpa de remolacha, semillas de linaza, minerales, aceite de salm\u00f3n, celulosa, krill ant\u00e1rtico seco (una fuente natural de EPA y DHA), manzana seca, MOS (mannan-oligosac\u00e1ridos), harina de algarroba, mezcla de extracto de plantas (rosmarinus sp., vitis sp., c\u00farcuma sp., citrus sp., Eugenia sp.), extracto de silimarina, clorhidrato de glucosamina, sulfato de condroitina, GLM (mejill\u00f3n de labios verdes).<\/p>\n<table class=\"table table-striped\">\n<tbody>\n<tr>\n<td>Prote\u00edna cruda (m\u00ednimo)<\/td>\n<td>26%<\/td>\n<\/tr>\n<tr>\n<td>Aceites y grasas crudas (m\u00ednimo)<\/td>\n<td>16%<\/td>\n<\/tr>\n<tr>\n<td>\u00c1cidos grasos omega 6<\/td>\n<td>2,2%<\/td>\n<\/tr>\n<tr>\n<td>\u00c1cidos grasos omega 3<\/td>\n<td>0,5%<\/td>\n<\/tr>\n<tr>\n<td>Materia org\u00e1nica<\/td>\n<td>8,5%<\/td>\n<\/tr>\n<tr>\n<td>Fibra Cruda (m\u00e1ximo)<\/td>\n<td>3%<\/td>\n<\/tr>\n<tr>\n<td>Humedad (m\u00e1ximo)<\/td>\n<td>9%<\/td>\n<\/tr>\n<tr>\n<td>Calcio (m\u00ednimo)<\/td>\n<td>1,8%<\/td>\n<\/tr>\n<tr>\n<td>F\u00f3sforo (m\u00ednimo)<\/td>\n<td>1,3%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>BR For Dog Pure Adulto Razas Medianas es un alimento seco, completo para perros adultos de razas medianas. rroz blanco (26%), cordero deshidratado (13,5%), pollo deshidratado (13,5%), grasa animal (pollo), prote\u00edna de pollo hidrolizado, pulpa de remolacha, semillas de linaza, minerales, aceite de salm\u00f3n, celulosa, krill ant\u00e1rtico seco (una fuente natural de EPA y DHA), [&hellip;]<\/p>\n","protected":false},"featured_media":10687,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[]},"product_brand":[],"product_cat":[138],"product_tag":[],"class_list":["post-10683","product","type-product","status-publish","has-post-thumbnail","product_cat-br-concentrado-perros","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/product\/10683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/comments?post=10683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/media\/10687"}],"wp:attachment":[{"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/media?parent=10683"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/product_brand?post=10683"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/product_cat?post=10683"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/product_tag?post=10683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}