{"id":10678,"date":"2024-06-01T21:10:29","date_gmt":"2024-06-01T21:10:29","guid":{"rendered":"https:\/\/lamascoteriaonline.co\/shop\/?post_type=product&#038;p=10678"},"modified":"2024-06-01T21:15:04","modified_gmt":"2024-06-01T21:15:04","slug":"br-for-dog-adulto-raza-pequena","status":"publish","type":"product","link":"https:\/\/lamascoteriaonline.co\/shop\/product\/br-for-dog-adulto-raza-pequena\/","title":{"rendered":"Br For Dog Adulto Raza Peque\u00f1a"},"content":{"rendered":"<p><b>BR For Dog Pure Adulto Razas Peque\u00f1as<\/b>\u00a0es un alimento seco, completo para perros adultos de razas peque\u00f1as.<\/p>\n<p>Pollo deshidratado, arroz, trigo, guisantes, grasa animal (pollo), prote\u00edna de pollo hidrolizado, pulpa de remolacha, semillas de linaza, vitaminas y minerales, huevos secos enteros, aceite de salm\u00f3n, harina de pescado, levadura de cerveza seca, extracto de romero, extracto de semilla de uva, extracto de c\u00farcuma, extracto de silimarina, aceite de pomelo expresado, aceite de hoja de clavo.<\/p>\n<table class=\"table table-striped\">\n<tbody>\n<tr>\n<td>Prote\u00edna cruda (m\u00ednimo)<\/td>\n<td>24%<\/td>\n<\/tr>\n<tr>\n<td>Aceite y grasas crudas (m\u00ednimo)<\/td>\n<td>12%<\/td>\n<\/tr>\n<tr>\n<td>Materia inorg\u00e1nica (m\u00e1ximo)<\/td>\n<td>6%<\/td>\n<\/tr>\n<tr>\n<td>Fibra Cruda (m\u00e1ximo)<\/td>\n<td>3%<\/td>\n<\/tr>\n<tr>\n<td>Humedad (m\u00e1ximo)<\/td>\n<td>9%<\/td>\n<\/tr>\n<tr>\n<td>Calcio (m\u00ednimo)<\/td>\n<td>0,7%<\/td>\n<\/tr>\n<tr>\n<td>F\u00f3sforo (m\u00ednimo)<\/td>\n<td>0,6%<\/td>\n<\/tr>\n<tr>\n<td><strong>ADDITIVES (per kg) VITAMINS<\/strong><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Vitamina A<\/td>\n<td>20,000 IU<\/td>\n<\/tr>\n<tr>\n<td>Vitamina D3<\/td>\n<td>2,000 IU<\/td>\n<\/tr>\n<tr>\n<td>Vitamina E<\/td>\n<td>150 mg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>BR For Dog Pure Adulto Razas Peque\u00f1as\u00a0es un alimento seco, completo para perros adultos de razas peque\u00f1as. Pollo deshidratado, arroz, trigo, guisantes, grasa animal (pollo), prote\u00edna de pollo hidrolizado, pulpa de remolacha, semillas de linaza, vitaminas y minerales, huevos secos enteros, aceite de salm\u00f3n, harina de pescado, levadura de cerveza seca, extracto de romero, extracto [&hellip;]<\/p>\n","protected":false},"featured_media":10682,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[]},"product_brand":[],"product_cat":[138],"product_tag":[],"class_list":["post-10678","product","type-product","status-publish","has-post-thumbnail","product_cat-br-concentrado-perros","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/product\/10678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/comments?post=10678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/media\/10682"}],"wp:attachment":[{"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/media?parent=10678"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/product_brand?post=10678"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/product_cat?post=10678"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lamascoteriaonline.co\/shop\/wp-json\/wp\/v2\/product_tag?post=10678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}